{"id":6229,"date":"2025-08-05T22:19:46","date_gmt":"2025-08-05T19:19:46","guid":{"rendered":"https:\/\/birimler.atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/?page_id=6229"},"modified":"2025-08-05T22:19:46","modified_gmt":"2025-08-05T19:19:46","slug":"haberler","status":"publish","type":"page","link":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/haberler\/","title":{"rendered":"Haberler"},"content":{"rendered":"<form method=\"get\" class=\"row g-3\" style=\"margin-bottom: 20px;\"><div class=\"col-md-3\"><input type=\"text\" name=\"haber_ara\" class=\"form-control\" placeholder=\"Haber ara...\" value=\"\"><\/div><div class=\"col-md-3\"><input type=\"date\" name=\"baslangic_tarihi\" class=\"form-control\" value=\"\"><\/div><div class=\"col-md-3\"><input type=\"date\" name=\"bitis_tarihi\" class=\"form-control\" value=\"\"><\/div><div class=\"col-md-3\"><button type=\"submit\" class=\"btn btn-secondary w-50\">Filtrele<\/button><\/div><\/form><ul class=\"kategori-yazilari-liste\"><li>Bu kategoride haber bulunmamaktad\u0131r.<\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6229","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/pages\/6229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/comments?post=6229"}],"version-history":[{"count":1,"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/pages\/6229\/revisions"}],"predecessor-version":[{"id":6230,"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/pages\/6229\/revisions\/6230"}],"wp:attachment":[{"href":"https:\/\/atauni.edu.tr\/egitim-bilimleri-anabilim-dali\/wp-json\/wp\/v2\/media?parent=6229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}